<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
{"id":26240,"date":"2017-09-15T15:30:13","date_gmt":"2017-09-15T13:30:13","guid":{"rendered":"https:\/\/www.engrenages.eu\/?post_type=profile&#038;p=26240"},"modified":"2023-11-14T12:52:55","modified_gmt":"2023-11-14T11:52:55","slug":"celine-mousseau","status":"publish","type":"profile","link":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/","title":{"rendered":"C\u00e9line Mousseau"},"content":{"rendered":"<div id=\"cmsmasters_row_a259ff8869\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_89f0b26c5a\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>En 1984, C\u00e9line a dix ans&nbsp;: comme beau\u00adcoup de sa g\u00e9n\u00e9\u00adra\u00adtion, gr\u00e2ce \u00e0 l\u2019\u00e9mission t\u00e9l\u00e9\u00advi\u00ads\u00e9e \u201cHip-Hop\u201d, pr\u00e9\u00adsen\u00adt\u00e9e par Syd\u00adney, elle plonge dans le chau\u00addron du hip-hop, dont elle res\u00adsort dot\u00e9e des super-pou\u00advoirs qui l\u2019animent tou\u00adjours aujourd\u2019hui pour assu\u00adrer la direc\u00adtion d\u2019Engrenage[s].<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_a186e4f249\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_ace33c44d6\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg\"><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_xa94u10hhr\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_sf62f20t8s\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>Apr\u00e8s une for\u00adma\u00adtion en com\u00admu\u00adni\u00adca\u00adtion, action cultu\u00adrelle et m\u00e9dia\u00adtion artis\u00adtique, elle tra\u00advaille de 1996 \u00e0 2002 pour les com\u00adpa\u00adgnies Science 89 (th\u00e9\u00e2tre, Nantes), Nomad (danse hip hop), la sc\u00e8ne natio\u00adnale de S\u00e9nart, comme char\u00adg\u00e9e de com\u00admu\u00adni\u00adca\u00adtion puis des rela\u00adtions avec les publics, pour la Com\u00adpa\u00adgnie Arti\u00adcu\u00adla\u00adtions \u2013 Zaza Dis\u00addier (danse hip-hop) et l\u2019ADDM 22, comme char\u00adg\u00e9e de mis\u00adsion hip-hop. En 2002, elle ren\u00adcontre le dan\u00adseur Fran\u00adco&nbsp;: c\u2019est le d\u00e9but d\u2019une grande com\u00adpli\u00adci\u00adt\u00e9 humaine et artis\u00adtique qui don\u00adne\u00adra nais\u00adsance \u00e0 la Com\u00adpa\u00adgnie Engre\u00adnage, deve\u00adnue depuis Engrenage[s].<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>En 1984, C\u00e9line a dix ans&nbsp;: comme beau\u00adcoup de sa g\u00e9n\u00e9\u00adra\u00adtion, gr\u00e2ce \u00e0 l\u2019\u00e9mission t\u00e9l\u00e9\u00advi\u00ads\u00e9e \u201cHip-Hop\u201d, pr\u00e9\u00adsen\u00adt\u00e9e par Syd\u00adney, elle plonge dans le chau\u00addron du hip-hop, dont elle res\u00adsort dot\u00e9e des super-pou\u00advoirs qui l\u2019animent tou\u00adjours aujourd\u2019hui pour assu\u00adrer la direc\u00adtion d\u2019Engrenage[s].<\/p>\n","protected":false},"featured_media":24387,"menu_order":1,"comment_status":"closed","ping_status":"open","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"pl-categs":[183],"class_list":["post-26240","profile","type-profile","status-publish","has-post-thumbnail","hentry","pl-categs-administrative-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\" \/>\n<meta property=\"og:description\" content=\"En 1984, C\u00e9line a dix ans : comme beaucoup de sa g\u00e9n\u00e9ration, gr\u00e2ce \u00e0 l\u2019\u00e9mission t\u00e9l\u00e9vis\u00e9e \u201cHip-Hop\u201d, pr\u00e9sent\u00e9e par Sydney, elle plonge dans le chaudron du hip-hop, dont elle ressort dot\u00e9e des super-pouvoirs qui l\u2019animent toujours aujourd\u2019hui pour assurer la direction d\u2019Engrenage[s].\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/\" \/>\n<meta property=\"og:site_name\" content=\"Engrenage[s]\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/engrenagesrennes\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T11:52:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"765\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/\",\"name\":\"C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/celine-mousseau.jpg\",\"datePublished\":\"2017-09-15T13:30:13+00:00\",\"dateModified\":\"2023-11-14T11:52:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/celine-mousseau.jpg\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/celine-mousseau.jpg\",\"width\":765,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/celine-mousseau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profiles\",\"item\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/profil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00e9line Mousseau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"name\":\"Engrenage[s]\",\"description\":\"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\",\"name\":\"Engrenage[s]\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"width\":400,\"height\":100,\"caption\":\"Engrenage[s]\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/engrenagesrennes\",\"https:\\\/\\\/www.instagram.com\\\/engrenages_rennes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagnieengrenage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/","og_locale":"en_US","og_type":"article","og_title":"C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","og_description":"En 1984, C\u00e9line a dix ans : comme beaucoup de sa g\u00e9n\u00e9ration, gr\u00e2ce \u00e0 l\u2019\u00e9mission t\u00e9l\u00e9vis\u00e9e \u201cHip-Hop\u201d, pr\u00e9sent\u00e9e par Sydney, elle plonge dans le chaudron du hip-hop, dont elle ressort dot\u00e9e des super-pouvoirs qui l\u2019animent toujours aujourd\u2019hui pour assurer la direction d\u2019Engrenage[s].","og_url":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/","og_site_name":"Engrenage[s]","article_publisher":"https:\/\/www.facebook.com\/engrenagesrennes","article_modified_time":"2023-11-14T11:52:55+00:00","og_image":[{"width":765,"height":430,"url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/","url":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/","name":"C\u00e9line Mousseau - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","isPartOf":{"@id":"https:\/\/www.engrenages.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/#primaryimage"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg","datePublished":"2017-09-15T13:30:13+00:00","dateModified":"2023-11-14T11:52:55+00:00","breadcrumb":{"@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/#primaryimage","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/celine-mousseau.jpg","width":765,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/www.engrenages.eu\/en\/profil\/celine-mousseau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.engrenages.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Profiles","item":"https:\/\/www.engrenages.eu\/en\/profil\/"},{"@type":"ListItem","position":3,"name":"C\u00e9line Mousseau"}]},{"@type":"WebSite","@id":"https:\/\/www.engrenages.eu\/en\/#website","url":"https:\/\/www.engrenages.eu\/en\/","name":"Engrenage[s]","description":"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","publisher":{"@id":"https:\/\/www.engrenages.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.engrenages.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.engrenages.eu\/en\/#organization","name":"Engrenage[s]","url":"https:\/\/www.engrenages.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","width":400,"height":100,"caption":"Engrenage[s]"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/engrenagesrennes","https:\/\/www.instagram.com\/engrenages_rennes\/","https:\/\/www.youtube.com\/user\/compagnieengrenage"]}]}},"_links":{"self":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/profile\/26240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/profile"}],"about":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/types\/profile"}],"replies":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/comments?post=26240"}],"version-history":[{"count":0,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/profile\/26240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media\/24387"}],"wp:attachment":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media?parent=26240"}],"wp:term":[{"taxonomy":"pl-categs","embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pl-categs?post=26240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}