<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
{"id":26014,"date":"2017-09-14T05:50:48","date_gmt":"2017-09-14T03:50:48","guid":{"rendered":"https:\/\/www.engrenages.eu\/?page_id=26014"},"modified":"2024-11-21T17:34:56","modified_gmt":"2024-11-21T16:34:56","slug":"artistic-actions-and-territorial-projects","status":"publish","type":"page","link":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/","title":{"rendered":"Artistic actions and territorial projects"},"content":{"rendered":"<div id=\"cmsmasters_row_3p0zm3elqz\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_vt2l979x4t\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_fb_5usk2j8eds\" class=\"cmsmasters_featured_block\">\n<div class=\"featured_block_inner\">\n<div class=\"featured_block_text\">\n<p style=\"text-align: left;\">Engrenage[s] pro\u00adpose une palette large et colo\u00adr\u00e9e d\u2019actions de sen\u00adsi\u00adbi\u00adli\u00adsa\u00adtion aux pra\u00adtiques artis\u00adtiques telles que danse hip-hop, graf\u00adfi\u00adti, musiques cui\u00advr\u00e9es, cr\u00e9a\u00adtion de cos\u00adtumes \/ sc\u00e9\u00adno\u00adgra\u00adphie tex\u00adtile\u2026<\/p>\n<p style=\"text-align: left;\">Cr\u00e9a\u00adtion ama\u00adteur, ate\u00adliers d\u2019initiation, for\u00adma\u00adtion pro\u00adfes\u00adsion\u00adnelle en danse\u2026 Nos artistes savent et aiment trans\u00admettre.<\/p>\n<p style=\"text-align: left;\">Chaque action est ax\u00e9e sur la d\u00e9cou\u00adverte et l\u2019apprentissage de tech\u00adniques mais aus\u00adsi sur la sen\u00adsi\u00adbi\u00adli\u00adsa\u00adtion \u00e0 la culture \u00e0 laquelle elles appar\u00adtiennent. L\u2019action peut ame\u00adner les publics \u00e0 une pro\u00adduc\u00adtion, des repr\u00e9\u00adsen\u00adta\u00adtions ou s\u2019inscrire dans un pro\u00adjet plu\u00adri\u00addis\u00adci\u00adpli\u00adnaire.<\/p>\n<p><strong>Engrenage[s] dis\u00adpose d\u2019un poten\u00adtiel de res\u00adsources et d\u2019imagination \u00e0 toute \u00e9preuve pour construire de v\u00e9ri\u00adtables pro\u00adjets cultu\u00adrels de proxi\u00admi\u00adt\u00e9 et pour tous les publics&nbsp;! N\u2019h\u00e9sitez pas \u00e0 nous contac\u00adter pour construire ensemble votre pro\u00adjet&nbsp;: contact@engrenages.eu \u2013 02 22 03 02 13<\/strong><\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_cg2lhhedv\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_1knaphpx4w\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_button_6hj3qdidtf\" class=\"button_wrap\"><a href=\"https:\/\/drive.google.com\/file\/d\/1sdICdU0j4gIqsGg-ajfcGiH3KoY3tEEW\/view?usp=drive_link\" class=\"cmsmasters_button\"><span>CATALOGUE D\u2019ACTIONS<\/span><\/a><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_qh7nx4r3ri\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_button_60ce92ruwc\" class=\"button_wrap\"><a href=\"https:\/\/drive.google.com\/file\/d\/1iTSxbtJKHtLGkSBdpQik87OEc48SzC_w\/view?usp=drive_link\" class=\"cmsmasters_button\"><span>DOSSIER P\u00c9DAGOGIQUE<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_0rcc2uvfye\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_vs71vanpl\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p>Engrenage[s] est r\u00e9f\u00e9\u00adren\u00adc\u00e9 sur Pass Culture, pour plus d\u2019in\u00adfor\u00adma\u00adtions c\u2019est par ici&nbsp;: <a href=\"https:\/\/pass.culture.fr\/espace-professeurs\/\">https:\/\/pass.culture.fr\/espace-professeurs\/<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-28023 alignleft\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/pass-culture.png\" alt width=\"202\" height=\"46\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/pass-culture.png 383w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/pass-culture-300x68.png 300w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\"><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_68l9vdz08d\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_q8zk1r8aa\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_hover_slider_zhmo4r6hsp\" class=\"cmsmasters_hover_slider\" data-thumb-width=\"100\" data-thumb-height=\"60\" data-active-slide=\"1\" data-pause-time=\"5000\" data-pause-on-hover=\"true\"><ul class=\"cmsmasters_hover_slider_items\">\n<li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"808\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/7B068A4E-A76E-410E-9703-4E6CE7F6EB8E-808x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142334-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142334-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142334-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Communaute-cGerard_Payelle-Villejean-24-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Communaute-cGerard_Payelle-Villejean-24-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Communaute-cGerard_Payelle-Villejean-24-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG-3124-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG-3124-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG-3124-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Red_Line_Crossers_WeAre_A.DUQUESNEL2022-6-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Red_Line_Crossers_WeAre_A.DUQUESNEL2022-6-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Red_Line_Crossers_WeAre_A.DUQUESNEL2022-6-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Le-Funk-Prend-Les-Rennes-2023_Jour1-c-Thomas-Guionnet-66-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Le-Funk-Prend-Les-Rennes-2023_Jour1-c-Thomas-Guionnet-66-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Le-Funk-Prend-Les-Rennes-2023_Jour1-c-Thomas-Guionnet-66-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-860x500.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-860x500.jpeg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-1160x675.jpeg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4698-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4698-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4698-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4625-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4625-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_4625-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2024\/02\/6-parade-Basse-Def-NicoM-2-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"Parade du Bal des Oiseaux (c) NicoM\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2024\/02\/6-parade-Basse-Def-NicoM-2-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2024\/02\/6-parade-Basse-Def-NicoM-2-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><\/ul>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_k5kuj01yr2\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_5dm6bui1t8\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\">\n<div id=\"cmsmasters_divider_gcjqzhoyza\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div class=\"cmsmasters_text\">\n<p>La trans\u00admis\u00adsion est au c\u0153ur du pro\u00adjet d\u2019Engrenage[s], enra\u00adci\u00adn\u00e9e dans une volon\u00adt\u00e9 tenace de ren\u00adcontre avec les publics. Elle se base sur une exp\u00e9\u00adrience solide de la m\u00e9dia\u00adtion entre pro\u00adjets artis\u00adtiques, cultu\u00adrels et sociaux. Elle s\u2019adapte aux ter\u00adri\u00adtoires et aux publics, \u00e0 l\u2019\u00e9coute des enjeux des par\u00adte\u00adnaires et des pro\u00adjets.<\/p>\n<p>Les actions artis\u00adtiques peuvent accom\u00adpa\u00adgner un spec\u00adtacle (comme un ate\u00adlier com\u00adplice pour s\u2019initier \u00e0 quelques pas de danse en amont) ou \u00eatre con\u00e7us \u00ab&nbsp;\u00e0 la carte&nbsp;\u00bb en fonc\u00adtion de la demande (comme un pro\u00adjet sco\u00adlaire de d\u00e9cou\u00adverte des cultures urbaines).<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_c6opaj22k\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_omqr3nlwr\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<h3><strong>Voici quelques exemples,<br>\n<\/strong><strong>Cliquez sur les titres pour en d\u00e9couvrir plus sur les projets<\/strong><\/h3>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_z9ulvxxf9\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_8b3uey3fns\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<h5><a href=\"https:\/\/www.engrenages.eu\/en\/projet\/communaute\/\"><strong>COMMUNAUT\u00c9 <\/strong>\u21f2 <\/a><\/h5>\n<p>avec la par\u00adti\u00adci\u00adpa\u00adtion de dan\u00adseurs ama\u00adteurs figu\u00adrants gr\u00e2ce au dis\u00adpo\u00adsi\u00adtif \u00ab&nbsp;Les Ren\u00adnais Prennent l\u2019Art&nbsp;\u00bb dans le cadre du fes\u00adti\u00adval \u00ab&nbsp;Rennes au plu\u00adriel, le ren\u00addez-vous de l\u2019\u00e9\u00adga\u00adli\u00adt\u00e9 et de la diver\u00adsi\u00adt\u00e9&nbsp;\u00bb.<\/p>\n<\/div>\n<div id=\"cmsmasters_video_wrap_\" class=\"cmsmasters_video_wrap\">\n<iframe loading=\"lazy\" title=\"COMMUNAUT\u00c9 - EXTRAITS\" width=\"1160\" height=\"653\" src=\"https:\/\/www.youtube.com\/embed\/SBU695_nvxw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n\n<div class=\"cmsmasters_text\">\n<h4><\/h4>\n<h5><a href=\"https:\/\/drive.google.com\/file\/d\/1lg41wFbtjOSoxA96A-eW9kS6BGpjzAtW\/view?usp=drive_link\"><strong>GOOD VIBES | MA\u00cbL MOREL et JEAN-NO\u00cbL PEDRON<\/strong><\/a> \u21f2<\/h5>\n<p>Dans le cadre de La Science sur les Planches 2023 \u2013 2024, <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">un pro\u00adjet pilo\u00adt\u00e9 par l\u2019Es\u00adpace des Sciences de Rennes avec le Col\u00adl\u00e8ge Pierre Oli\u00advier Mal\u00adherbe de Cha\u00adteau\u00adbourg<br>\n<strong>Ondes et fr\u00e9\u00adquences \u00e0 tra\u00advers la musique et le mou\u00adve\u00adment<\/strong><br>\n<\/span><\/p>\n<\/div>\n<div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-07-100613.png\"><\/div><div class=\"cmsmasters_text\">\n<h5><\/h5>\n<h5><a href=\"https:\/\/drive.google.com\/file\/d\/1-30UwkaAcMc92Ai4X4Yr8mbOUbN_F6Rr\/view\"><strong>TIOBAFELO <\/strong><\/a>\u21f2<\/h5>\n<p>Pro\u00adjet EAC \u00e0 l\u2019\u00e9\u00adcole Louise Briand de Broons<br>\nFinan\u00adc\u00e9 par le d\u00e9par\u00adte\u00adment d\u2019Ille et Vilaine<br>\n<strong>Tra\u00advail autour de la cr\u00e9a\u00adtion cho\u00adr\u00e9\u00adgra\u00adphique&nbsp;<\/strong><\/p>\n<\/div>\n<div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Capture2.png\"><\/div><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<h5>RED LINE CROSSERS \u2013 \u00ab&nbsp;We are New Orleans&nbsp;\u00bb<\/h5>\n<p>R\u00e9si\u00addence mis\u00adsion avec les habitant\u00b7es de Lif\u00adfr\u00e9-Cor\u00admier Com\u00admu\u00adnau\u00adt\u00e9, les \u00e9coles de musique La Fabrik et L\u2019Orph\u00e9on, la ville de la Bouexi\u00e8re, le ser\u00advice cultu\u00adrel de Lif\u00adfr\u00e9 et l\u2019Espace Bel Air de St-Aubin-du-Cor\u00admier<br>\nFinan\u00adc\u00e9 par le d\u00e9par\u00adte\u00adment d\u2019Ille et Vilaine et les par\u00adte\u00adnaires du ter\u00adri\u00adtoire<br>\n<strong>D\u00e9cou\u00adverte de la culture, de la musique cui\u00advr\u00e9e et de la danse de la Nou\u00advelle Orl\u00e9ans \u21d2<\/strong><\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_76l5l160ni\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<h5><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1RJspTgnk-GdgDwpkY7t4D21F40Balg-0\/view\">KINYONGA <\/a>\u21f2<\/strong><\/h5>\n<p>Pro\u00adjet EAC au col\u00adl\u00e8ge Mor\u00advan Lebesque \u2013 Mor\u00addelles<br>\nFinan\u00adc\u00e9 par le d\u00e9pa\u00adre\u00adment d\u2019Ille et Vilaine<br>\n<strong>Tra\u00advail autour du chant, de la musique et de la danse en vue de tour\u00adner un clip<\/strong><\/p>\n<\/div>\n<div id=\"cmsmasters_video_wrap_\" class=\"cmsmasters_video_wrap\">\n<iframe loading=\"lazy\" title=\"CLIP - R\u00e9sultat du projet EAC entre Kinyonga et le coll\u00e8ge Morvan Lebesque de Mordelles\" width=\"1160\" height=\"653\" src=\"https:\/\/www.youtube.com\/embed\/ALVQRLLYhHM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n\n<div class=\"cmsmasters_text\">\n<h5><a href=\"https:\/\/drive.google.com\/file\/d\/1D3WIL2w2qNQpDoW3MGyJaI4ERPjAuuNA\/view\"><strong>TIOBAFELO ET COMMUNAUT\u00c9<\/strong> <\/a>\u21f2<\/h5>\n<p>Pro\u00adjet EAC \u00e0 l\u2019\u00e9\u00adcole Paul Gau\u00adguin \u2013 Saint Aubin d\u2019Au\u00adbi\u00adgn\u00e9<br>\nFinan\u00adc\u00e9 par le d\u00e9par\u00adte\u00adment d\u2019Ille et Vilaine<br>\n<strong>Cr\u00e9a\u00adtion cho\u00adr\u00e9\u00adgra\u00adphique et d\u00e9am\u00adbu\u00adla\u00adtion en lien avec le patri\u00admoine de la ville&nbsp;<\/strong><\/p>\n<\/div>\n<div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/ST-AUBIN.png\"><\/div><div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<h5><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1lwgSkdEYopWDLIIjdPRftyvyoGsz7sN-\/view?usp=drive_link\">NIOMOYE <\/a><\/strong><a href=\"https:\/\/drive.google.com\/file\/d\/1lwgSkdEYopWDLIIjdPRftyvyoGsz7sN-\/view?usp=drive_link\"><strong>\u21f2&nbsp;<\/strong><\/a><\/h5>\n<p>Pro\u00adjet EAC au col\u00adl\u00e8ge \u00c9change \u2013 Rennes<br>\nEn par\u00adte\u00adna\u00adriat avec Les Tom\u00adb\u00e9es de la Nuit et finan\u00adc\u00e9 par le d\u00e9par\u00adte\u00adment d\u2019Ille et Vilaine.<br>\n<strong>D\u00e9cou\u00adverte des m\u00e9tier de la musique et par\u00adti\u00adci\u00adpa\u00adtion \u00e0 un clip<\/strong><\/p>\n<\/div>\n<div id=\"cmsmasters_video_wrap_\" class=\"cmsmasters_video_wrap\">\n<iframe loading=\"lazy\" title=\"Mon Corps - Niomoye\" width=\"1160\" height=\"653\" src=\"https:\/\/www.youtube.com\/embed\/eHBUWVrj9B4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n\n<div id=\"cmsmasters_video_wrap_\" class=\"cmsmasters_video_wrap\">\n<iframe loading=\"lazy\" title=\"&quot;We Are New Orleans ! &quot; - Parade du 26 mai 2019 \u00e0 Saint-Aubin-du-Cormier\" width=\"1160\" height=\"653\" src=\"https:\/\/www.youtube.com\/embed\/nAlyu7dXByI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_aexteweevf\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_n9t700k18c\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">R\u00c9SIDENCE MISSION \u21f2<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>\u00c0 l\u2019oc\u00adca\u00adsion de la cr\u00e9a\u00adtion du Bal des Oiseaux, nous avons mis en place une r\u00e9si\u00addence mis\u00adsion avec Rue des Arts.<\/p>\n<p>Un pro\u00adjet coor\u00addon\u00adn\u00e9 par Rue des Arts, avec le sou\u00adtien de&nbsp;: Roche aux F\u00e9es Com\u00admu\u00adnau\u00adt\u00e9, le d\u00e9par\u00adte\u00adment d\u2019ille-et-vilaine, fon\u00adda\u00adtion Trans\u00addev, les Villes de Mou\u00adlins, Mar\u00adcill\u00e9 Robert, La-Guerche-de-Bre\u00adtagne, Jan\u00adz\u00e9<\/p>\n<p>LE BAL DES OISEAUX ET RUE DES ARTS&nbsp;: Une r\u00e9si\u00addence-mis\u00adsion sur 2 ans<br>\nZoom sur le dis\u00adpo\u00adsi\u00adtif de r\u00e9si\u00addence \u2013 mis\u00adsion&nbsp;:<br>\nDis\u00adpo\u00adsi\u00adtif du Conseil D\u00e9par\u00adte\u00admen\u00adtal 35 en sou\u00adtien \u00e0 une com\u00adpa\u00adgnie en cr\u00e9a\u00adtion<br>\nSou\u00adtien finan\u00adcier de 7000 \u20ac mini\u00admum par les col\u00adlec\u00adti\u00advi\u00adt\u00e9s locales<br>\nPar\u00adti\u00adci\u00adpa\u00adtion finan\u00adci\u00e8re du CD 35 \u00e0 la m\u00eame hau\u00adteur que les col\u00adlec\u00adti\u00advi\u00adt\u00e9s<br>\nCom\u00adbine \u00ab&nbsp;dif\u00adfu\u00adsion, cr\u00e9a\u00adtion, action cultu\u00adrelle&nbsp;\u00bb<br>\nEntre novembre 2022 et juin 2023 sur le Pays de Vitr\u00e9 (Vitr\u00e9 com\u00admu\u00adnau\u00adt\u00e9 + Roche aux F\u00e9es com\u00admu\u00adnau\u00adt\u00e9) :<\/p>\n<p><strong>CR\u00c9ATION<\/strong><br>\n12 jour\u00adn\u00e9es d\u00e9di\u00e9es au tra\u00advail de cr\u00e9a\u00adtion tex\u00adtile, musi\u00adcale et artis\u00adtique en vue de la cr\u00e9a\u00adtion du Bal des Oiseaux<\/p>\n<p><strong>ACTIONS CULTURELLES AVEC DES PUBLICS DE 7 \u00c0 97 ANS<\/strong><br>\n&gt; 20 heures d\u2019ateliers de cr\u00e9a\u00adtion de cos\u00adtumes ani\u00adm\u00e9es par 2 cos\u00adtu\u00admi\u00e8res avec<br>\n\u2013 10 per\u00adsonnes avec han\u00addi\u00adcap cog\u00adni\u00adtif (foyer de vie de Mar\u00adti\u00adgn\u00e9-Fd et habi\u00adtat inclu\u00adsif)<br>\n\u2013 6 per\u00adsonnes migrantes<br>\n\u2013 20 jeunes (3 struc\u00adtures jeu\u00adnesse)<br>\n\u2013 8 r\u00e9sident\u00b7es d\u2019EHPAD (cos\u00adtu\u00admi\u00e8res \u00ab&nbsp;en immer\u00adsion&nbsp;\u00bb au sein de l\u2019EHPAD)<br>\n\u2013 2 classes pri\u00admaire<br>\n\u2013 6 per\u00adsonnes sui\u00advies par le Conseil D\u00e9par\u00adte\u00admen\u00adtal d\u2019Action Sociale<br>\n\u2013 envi\u00adron 10 per\u00adsonnes volon\u00adtaires du ter\u00adri\u00adtoire<\/p>\n<p>&gt; 9 heures d\u2019ateliers de cr\u00e9a\u00adtion musi\u00adcale avec 4 \u00e9l\u00e8ves du Hang\u2019art, \u00e9cole de musique<\/p>\n<p>&gt; 16 heures de \u00ab&nbsp;Cir\u00adcle\u00adsongs&nbsp;\u00bb avec<\/p>\n<p>- 20 habitant\u00b7es volon\u00adtaires de la Guerche de Bre\u00adtagne<br>\n\u2013 12 jeunes de l\u2019\u00e9quipe f\u00e9mi\u00adnine junior de vol\u00adley de l\u2019ESC Mou\u00adlins<br>\n\u2013 12 membres de la sec\u00adtion th\u00e9\u00e2tre de l\u2019ESC Mou\u00adlins<br>\n\u2013 20 per\u00adsonnes dans le cadre des \u00ab&nbsp;ani\u00adma\u00adtions seniors&nbsp;\u00bb du conseil com\u00admu\u00adnal d\u2019action sociale de Retiers<br>\n\u2013 6 membres de la cho\u00adrale \u00ab&nbsp;de la Bel\u00adlouye&nbsp;\u00bb de Retiers<br>\n\u2013 10 per\u00adsonnes volon\u00adtaires du Bis\u00adtrot Lab de Co\u00ebsmes (2 ses\u00adsions)<\/p>\n<p>&gt; 8 heures d\u2019ateliers de th\u00e9\u00e2tre de choeur \/ figu\u00adra\u00adtion avec<\/p>\n<p>- 10 habitant\u00b7es volon\u00adtaires, de 14 \u00e0 79 ans<br>\n\u2013 4 habitant\u00b7es de la struc\u00adture d\u2019habitat inclu\u00adsif FILEAS<\/p>\n<p><strong>DIFFUSION<\/strong><br>\n&gt; sor\u00adtie du Bal des Oiseaux le 24\/06\/23 \u00e0 Mou\u00adlins avec la par\u00adti\u00adci\u00adpa\u00adtion des figurant\u00b7es dans une \u00ab&nbsp;pro\u00adces\u00adsion&nbsp;\u00bb<br>\net des porteur\u00b7es des cos\u00adtumes r\u00e9a\u00adli\u00ads\u00e9s pen\u00addant l\u2019ann\u00e9e<\/p>\n<p><strong>LES \u00c0 C\u00d4T\u00c9S<\/strong><br>\n&gt; une r\u00e9p\u00e9\u00adti\u00adtion g\u00e9n\u00e9\u00adrale le ven\u00addre\u00addi 23 juin ouverte avec la pr\u00e9\u00adsence des r\u00e9sident\u00b7es de l\u2019EHPAD ayant<br>\npar\u00adti\u00adci\u00adp\u00e9 aux ate\u00adliers de cr\u00e9a\u00adtion tex\u00adtile<br>\n&gt; d\u00eener du ven\u00addre\u00addi 23\/06 sur le site du spec\u00adtacle avec les b\u00e9n\u00e9\u00advoles du fes\u00adti\u00adval d\u00e9sar\u00adti\u00adcu\u00adl\u00e9, les artistes du Bal<br>\ndes Oiseaux, les figurant\u00b7es du Bal des Oiseaux, les r\u00e9sident\u00b7es de l\u2019EHPAD (soit une cen\u00adtaine de per\u00adsonnes<br>\nenvi\u00adron)<br>\n&gt; des par\u00adte\u00adna\u00adriats qui se nouent pour l\u2019avenir sans l\u2019interm\u00e9diaire de Rue des Arts (entre EHPAD et BDO, entre<br>\nCDAS et BDO)<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><div id=\"cmsmasters_hover_slider_n6a3btqru7\" class=\"cmsmasters_hover_slider\" data-thumb-width=\"100\" data-thumb-height=\"60\" data-active-slide=\"1\" data-pause-time=\"5000\" data-pause-on-hover=\"true\"><ul class=\"cmsmasters_hover_slider_items\">\n<li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230105_143745-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230105_143745-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230105_143745-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142356-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142356-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/20230104_142356-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Hangart-technique-vocale-5-860x500.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Hangart-technique-vocale-5-860x500.jpeg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/Hangart-technique-vocale-5-1160x675.jpeg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-1-860x500.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-1-860x500.jpeg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/section-theatre-ESCM-1-1160x675.jpeg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_1654-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_1654-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/IMG_1654-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"500\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/P1110254-min-860x500.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/P1110254-min-860x500.jpg 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/12\/P1110254-min-1160x675.jpg 1160w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/figure><\/li><\/ul>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":24721,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-26014","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes<\/title>\n<meta name=\"description\" content=\"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\" \/>\n<meta property=\"og:description\" content=\"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/\" \/>\n<meta property=\"og:site_name\" content=\"Engrenage[s]\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/engrenagesrennes\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T16:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2018\/07\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/\",\"name\":\"Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg\",\"datePublished\":\"2017-09-14T03:50:48+00:00\",\"dateModified\":\"2024-11-21T16:34:56+00:00\",\"description\":\"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/artistic-actions-and-territorial-projects\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artistic actions and territorial projects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"name\":\"Engrenage[s]\",\"description\":\"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\",\"name\":\"Engrenage[s]\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"width\":400,\"height\":100,\"caption\":\"Engrenage[s]\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/engrenagesrennes\",\"https:\\\/\\\/www.instagram.com\\\/engrenages_rennes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagnieengrenage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","description":"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/","og_locale":"en_US","og_type":"article","og_title":"Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","og_description":"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...","og_url":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/","og_site_name":"Engrenage[s]","article_publisher":"https:\/\/www.facebook.com\/engrenagesrennes","article_modified_time":"2024-11-21T16:34:56+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2018\/07\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/","url":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/","name":"Artistic actions and territorial projects - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","isPartOf":{"@id":"https:\/\/www.engrenages.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/#primaryimage"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/#primaryimage"},"thumbnailUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2018\/07\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg","datePublished":"2017-09-14T03:50:48+00:00","dateModified":"2024-11-21T16:34:56+00:00","description":"Engrenage[s] propose une palette large et color\u00e9e d\u2019actions de sensibilisation aux pratiques artistiques telles que danse hip-hop, graffiti, musiques...","breadcrumb":{"@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/#primaryimage","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2018\/07\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2018\/07\/22-Maure-de-Bretagne-Cle\u0301ment-Harpillard-light.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.engrenages.eu\/en\/artistic-actions-and-territorial-projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.engrenages.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Artistic actions and territorial projects"}]},{"@type":"WebSite","@id":"https:\/\/www.engrenages.eu\/en\/#website","url":"https:\/\/www.engrenages.eu\/en\/","name":"Engrenage[s]","description":"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","publisher":{"@id":"https:\/\/www.engrenages.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.engrenages.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.engrenages.eu\/en\/#organization","name":"Engrenage[s]","url":"https:\/\/www.engrenages.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","width":400,"height":100,"caption":"Engrenage[s]"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/engrenagesrennes","https:\/\/www.instagram.com\/engrenages_rennes\/","https:\/\/www.youtube.com\/user\/compagnieengrenage"]}]}},"_links":{"self":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages\/26014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/comments?post=26014"}],"version-history":[{"count":0,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages\/26014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media\/24721"}],"wp:attachment":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media?parent=26014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}