<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
<br />
<b>Warning</b>:  Undefined variable $siteurl in <b>/home/engrenagrl/www/wp-config.php</b> on line <b>54</b><br />
{"id":26001,"date":"2017-09-07T15:03:41","date_gmt":"2017-09-07T13:03:41","guid":{"rendered":"https:\/\/www.engrenages.eu\/?page_id=26001"},"modified":"2025-09-16T10:20:12","modified_gmt":"2025-09-16T08:20:12","slug":"le-funk-prend-les-rennes","status":"publish","type":"page","link":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/","title":{"rendered":"Le Funk prend les Rennes"},"content":{"rendered":"<div id=\"cmsmasters_row_n0d35fgcq9\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_1pocmn92sn\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\">\n<div id=\"cmsmasters_divider_9q4utez8md\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/Capture-decran-Affiche-BD.png\"><\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_gsfxki2foi\" class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_column_inner\">\n<div id=\"cmsmasters_divider_97crlwva2n\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div class=\"cmsmasters_img  cmsmasters_image_n\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/08\/Flyer-Focus-Funk-2-scaled.png\"><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_uds4w1k039\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_kh6mrah30h\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<h4><strong>BILLETTERIES<\/strong>&nbsp;:<\/h4>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_u5nc1bfe6\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_ty3jdk028\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_button_ox83nck988\" class=\"button_wrap\"><a href=\"https:\/\/indiv.themisweb.fr\/0533\/fChoixSeanceWidget.aspx?idstructure=0533&amp;EventId=465&amp;request=QcE+w0WHSuCP7pZybTdhZNTpu\/3j7Fuo3f9d0FshdiMzKoWzuMLNBd+JS9HTH6OYbYyFSmvu1OQ=&amp;tn=90&amp;quHash=98dc9cc156ccb6c3887c26fc757b102dc411f1298546d4e975be2f67f1c97de5\" class=\"cmsmasters_button cmsmasters_but_clear_styles cmsmasters_but_bg_hover\" target=\"_blank\"><span>FOCUS FUNK \u2013 BATTLE<\/span><\/a><\/div>\n<div class=\"cmsmasters_text\">\n<p style=\"text-align: center;\"><sub>17h \u2013 19h<\/sub><br>\n<sub>Au Tri\u00adangle, cit\u00e9 de la danse<\/sub><br>\n<sub>Bou\u00adle\u00advard de You\u00adgo\u00adsla\u00advie<\/sub><br>\n<sub>35200 Rennes<\/sub><\/p>\n<p style=\"text-align: center;\"><sub>02&nbsp;99&nbsp;22&nbsp;27&nbsp;27<\/sub><\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_kctom2s7ib\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_button_ydsqmigezs\" class=\"button_wrap\"><a href=\"https:\/\/shotgun.live\/events\/focus-funk?utm_source=engrenages\" class=\"cmsmasters_button cmsmasters_but_clear_styles cmsmasters_but_bg_hover\" target=\"_blank\"><span>LE FUNK PREND LE B.A.M<\/span><\/a><\/div>\n<div class=\"cmsmasters_text\">\n<p style=\"text-align: center;\"><sup>21h \u2013 1h<\/sup><br>\n<sup>Au B.A.M (B\u00e2ti\u00adment \u00e0 Mode\u00adler)<\/sup><br>\n<sup>2 rue Andr\u00e9 Tras\u00adbot<\/sup><br>\n<sup>35200 Rennes<\/sup><\/p>\n<p style=\"text-align: center;\"><sup>Soi\u00adr\u00e9e en co-orga\u00adni\u00adsa\u00adtion avec Dooi\u00adnit Fes\u00adti\u00adval<\/sup><\/p>\n<\/div>\n<\/div><\/div>\n<div id=\"cmsmasters_column_4bsahcamu\" class=\"cmsmasters_column one_third\">\n<div class=\"cmsmasters_column_inner\"><div id=\"cmsmasters_button_fqkbra221\" class=\"button_wrap\"><a href=\"#\" class=\"cmsmasters_button cmsmasters_but_clear_styles cmsmasters_but_bg_hover\" target=\"_blank\"><span>STAGES DE LOCKING ET POPPING<\/span><\/a><\/div>\n<div class=\"cmsmasters_text\">\n<p style=\"text-align: center;\"><sup>10h-11h30 Locking<\/sup><br>\n<sup>11h30-13h Pop\u00adping<\/sup><br>\n<sup>Au Tri\u00adangle&nbsp;<\/sup><\/p>\n<p style=\"text-align: center;\"><sup>Ins\u00adcrip\u00adtion obli\u00adga\u00adtoire en envoyant un mail \u00e0<strong> contact@engrenages.eu<\/strong>,<br>\nmer\u00adci de pr\u00e9\u00adci\u00adser&nbsp;: nom\/pr\u00e9nom\/\u00e2ge\/num\u00e9ro de t\u00e9l\u00e9\u00adphone et \u00e0 quel(s) stage(s) vous sou\u00adhai\u00adtez \u00eatre inscrit\u00b7e<br>\npaie\u00adment sur place, le jour m\u00eame, en esp\u00e8ces<\/sup><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_eft83kb0lb\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_q1osibtbz\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Apr\u00e8s 6 \u00e9di\u00adtions du Funk Prend Les Rennes, entre 2012 et 2023, nous&nbsp;sommes contraint\u00b7es<\/span> de ne plus orga\u00adni\u00adser le fes\u00adti\u00adval pour le moment. En effet, l\u2019\u00e9conomie fra\u00adgile du sec\u00adteur cultu\u00adrel dans son ensemble et la baisse des sub\u00adven\u00adtions publiques, ne nous per\u00admet plus de main\u00adte\u00adnir ce ren\u00addez-vous local aim\u00e9 et recon\u00adnu, qui repr\u00e9\u00adsen\u00adtait un labo\u00adra\u00adtoire d\u2019id\u00e9es pour nos artistes et un ter\u00adrain de jeu pour notre savoir-faire en orga\u00adni\u00adsa\u00adtion d\u2019\u00e9v\u00e9nements.<\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><strong>Nous avons n\u00e9an\u00admoins sou\u00adhai\u00adt\u00e9 gar\u00adder un temps fort, qui main\u00adtienne le lien avec le public ren\u00adnais et les passionn\u00e9\u00b7es de groove<\/strong>.&nbsp;<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Forts du suc\u00adc\u00e8s du bat\u00adtle Focus Funk #1, inven\u00adt\u00e9 lors du Funk Prend les Rennes 2023, \u00e9v\u00e9\u00adne\u00adment in\u00e9dit \u00e0 Rennes et seul bat\u00adtle d\u00e9di\u00e9 au danses funk\u00adstyle de l\u2019Ouest, nous orga\u00adni\u00adsons&nbsp;<strong>une seconde \u00e9di\u00adtion le<\/strong><\/span><strong>&nbsp;<span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">same\u00addi 4 octobre 2025<\/span>&nbsp;<span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">dans le quar\u00adtier du Blosne, au Tri\u00adangle, Cit\u00e9 de la Danse.<\/span><\/strong><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Elle com\u00adpren\u00addra&nbsp;<strong>un<\/strong><\/span>&nbsp;<span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><strong>bat\u00adtle de danse funk\u00adstyle<\/strong>&nbsp;en deux par\u00adties<\/span><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">, avec les pr\u00e9-s\u00e9lec\u00adtions gra\u00adtuites \u00e0 l\u2019ext\u00e9rieur puis les qua\u00adli\u00adfi\u00adca\u00adtions dans la salle de spec\u00adtacle avec une entr\u00e9e sur billet\u00adte\u00adrie. Entre les deux, aura lieu&nbsp;<strong>un<\/strong><\/span><strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">&nbsp;soul train line par\u00adti\u00adci\u00adpa\u00adtif,<\/span>&nbsp;<\/strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><strong>construit avec des habitant\u00b7es com\u00adplices form\u00e9\u00b7es en amont<\/strong>&nbsp;par les danseur\u00b7euses d\u2019Engrenage[s].<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Pour cl\u00f4\u00adtu\u00adrer cette jour\u00adn\u00e9e c\u00e9l\u00e9\u00adbrant les cultures funk,&nbsp;<strong>nous sommes ravie\u00b7es de coor\u00adga\u00adni\u00adser&nbsp;<\/strong><\/span><strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">avec notre \u00ab&nbsp;cou\u00adsin&nbsp;\u00bb ren\u00adnais, Dooi\u00adnit Fes\u00adti\u00adval, une soi\u00adr\u00e9e DJ set 100% Funk au BAM&nbsp;!<\/span><\/strong><\/p>\n<p><em>Affiche \u00a9 Alexandre Lemagne<\/em><\/p>\n<p>Mer\u00adci \u00e0 tous nos par\u00adte\u00adnaires qui rendent cet \u00e9v\u00e9\u00adne\u00adment pos\u00adsible&nbsp;:<\/p>\n<p><strong>R\u00e9gion Bre\u00adtagne, Ville de Rennes, Le Tri\u00adangle cit\u00e9 de la Danse, Dooi\u00adnit Fes\u00adti\u00adval et l\u2019Apras<\/strong><\/p>\n<p><em>Nous en pro\u00adfi\u00adtons pour remer\u00adcier tous les par\u00adte\u00adnaires des autres \u00e9di\u00adtions qui ont per\u00admis au Funk Prend les Rennes d\u2019exis\u00adter depuis 2012&nbsp;! Bar Le Chan\u00adtier \u2013 Clair Obs\u00adcur \u2013 L\u2019An\u00adti\u00adpode, mai\u00adson des jeunes et des cultures \u2013 L\u2019H\u00f4tel Pas\u00adteur \u2013 L\u2019Institut Fran\u00adco Am\u00e9\u00adri\u00adcain \u2013 L\u2019U\u00adbu \u2013 La Mai\u00adson Bleue \u2013 La Mai\u00adson de quar\u00adtier de la Touche \u2013 La MJC Br\u00e9\u00adqui\u00adgny \u2013 La Paillette&nbsp; \u2013 Le CCNRB \u2013 Le Dia\u00adpa\u00adson&nbsp; \u2013 Le SIUAPS \u2013 Le Tam\u00adbour&nbsp; \u2013 Le Tri\u00adangle \u2013 Les Ate\u00adliers Du Vent \u2013 Les Biblio\u00adth\u00e8ques de Rennes \u2013 Les Champs Libres \u2013 Les Tom\u00adb\u00e9es de la Nuit \u2013 Les Uni\u00adver\u00adsi\u00adt\u00e9s de Rennes \u2013 Maca\u00addam Bas\u00adket \u2013&nbsp;<\/em><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_28foh6nk0r\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_23h7mp5d1i\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_accordion\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">LE FUNK PREND LES RENNES de 2012 \u00e0 2023<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Entre 2012 et 2023, Le Funk Prend les Rennes s\u2019est vou\u00adlue \u00eatre une r\u00e9f\u00e9\u00adrence de la pro\u00adgram\u00adma\u00adtion funk ren\u00adnaise. Chaque \u00e9di\u00adtion explore un nou\u00adveau pan de la cr\u00e9a\u00adtion funk et hip-hop, avec une dimen\u00adsion inter\u00adna\u00adtio\u00adnale et tou\u00adjours fes\u00adtive. L\u2019id\u00e9e&nbsp;: faire conna\u00eetre la vita\u00adli\u00adt\u00e9 des cultures funk et hip-hop.<\/p>\n<p>Le fes\u00adti\u00adval c\u2019est aus\u00adsi &nbsp;un \u00e9ven\u00adtail d\u2019actions cultu\u00adrelles (stages, ate\u00adliers, mas\u00adter\u00adclass, conf\u00e9\u00adrences\u2026) qui r\u00e9pond \u00e0 cette volon\u00adt\u00e9 d\u2019exis\u00adter pour et avec le public, avec des pro\u00adpo\u00adsi\u00adtions tou\u00adjours par\u00adti\u00adci\u00adpa\u00adtives et immer\u00adsives,<\/p>\n<p>C\u2019est enfin une plu\u00adra\u00adli\u00adt\u00e9 de par\u00adte\u00adna\u00adriats&nbsp;: salles de spec\u00adtacles, centres cultu\u00adrels, mai\u00adsons de quar\u00adtier, biblio\u00adth\u00e8ques, struc\u00adtures socio-cultu\u00adrelles.<\/p>\n<p>En r\u00e9su\u00adm\u00e9&nbsp;: un moment fort de convi\u00advia\u00adli\u00adt\u00e9 dans une optique citoyenne et de vivre ensemble.<\/p>\n<p>\u00c0 par\u00adcou\u00adrir cides\u00adsous, les archives et sou\u00adve\u00adnirs des \u00e9di\u00adtions ant\u00e9\u00adrieures\u2026<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_kw8dm3iilb\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_fiwdpssbl\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\">\n<div id=\"cmsmasters_divider_o69uj4bx76\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_0jubhac0ci\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_8zisoajc9q\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">LE FUNK PREND LES RENNES 2023 \u2013 \u00c9DITION DES 20 ANS D\u2032ENGRENAGES<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">&nbsp;&nbsp; Cette nou\u00advelle \u00e9di\u00adtion du Funk Prend les Rennes se d\u00e9roule sur une ann\u00e9e tr\u00e8s par\u00adti\u00adcu\u00adli\u00e8re&nbsp;: celle des <\/span><strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">20 ans d\u2019Engrenage[s]<\/span><\/strong> <span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">! Hors de ques\u00adtion de ne pas c\u00e9l\u00e9\u00adbrer cet anni\u00adver\u00adsaire et sur\u00adtout de le faire dans notre coin. Depuis ses d\u00e9buts, Engrenage[s] a pour voca\u00adtion de <\/span><strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">r\u00e9unir les gens autour du funk, du hip-hop et du groove<\/span><\/strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">, cette 6\u00e8me \u00e9di\u00adtion du fes\u00adti\u00adval ne fera pas excep\u00adtion.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Au d\u00e9part com\u00adpa\u00adgnie de danse, Engrenage[s] s\u2019est peu \u00e0 peu ouvert \u00e0 d\u2019autres dis\u00adci\u00adplines et est aujourd\u2019hui un bureau de pro\u00adduc\u00adtion qui accom\u00adpagne <\/span><strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">une ving\u00adtaine de pro\u00adjets artis\u00adtiques vari\u00e9s<\/span><\/strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">. Entre repr\u00e9\u00adsen\u00adta\u00adtions et actions cultu\u00adrelles, sur sc\u00e8ne ou dans la rue, tout est fait pour venir \u00e0 la ren\u00adcontre du public, de tous les publics et 20 ans apr\u00e8s il sont nom\u00adbreux, ceux qui ont croi\u00ads\u00e9 la route de nos artistes. Gr\u00e2ce \u00e0 nos par\u00adte\u00adnaires ren\u00adnais fid\u00e8les, nous avons sou\u00adhai\u00adt\u00e9 rendre hom\u00admage \u00e0 tout ce tra\u00advail et \u00e0 ces moments de par\u00adtage. Pen\u00addant 5 jours nous avons ima\u00adgi\u00adn\u00e9 un pro\u00adgramme \u00e0 notre image&nbsp;: <\/span><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">\u00e9clec\u00adtique et fes\u00adtif<\/span><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\"> qui sau\u00adra, on l\u2019esp\u00e8re, nous r\u00e9unir tous.tes.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Conf\u00e9\u00adrence, concerts, JAM, DJ Sets, Bloc<\/span><\/strong><strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">k Par\u00adty, cos\u00adtu\u00adme\u00adrie, ate\u00adliers, Soul Train, bat\u00adtle, brass band<\/span><\/strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">\u2026<\/span><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\"> tout ce qui fait l\u2019ADN d\u2019Engrenage[s], depuis toutes ces ann\u00e9es, est r\u00e9uni pour f\u00eater avec vous<\/span> <strong><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">20 ans d\u2019histoire com\u00admune et de groove&nbsp;!<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/07\/Dossier-de-presse-le-Funk-Prend-les-Rennes.pdf\">Dos\u00adsier de presse \u2013 le Funk Prend les Rennes<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/drive.google.com\/file\/d\/17MB2IcRLMjsh28m9gqO-i01751BytDjF\/view?usp=sharing\">Album Pho\u00adto pour revivre cette 6\u00e8me \u00e9di\u00adtion<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Vid\u00e9os After Partys<\/strong><\/h4>\n<p>R\u00e9a\u00adli\u00adsa\u00adtion&nbsp;: Mor\u00adgane Michotte&nbsp;:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Q7PP3qEcRNo\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29978 alignnone\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.10.05\u202fPM.png\" alt width=\"335\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.10.05\u202fPM.png 608w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.10.05\u202fPM-300x175.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.10.05\u202fPM-580x338.png 580w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\"> &nbsp;<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=0DZsTK2Zc40&amp;t=1s\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29975 alignnone\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.04.39\u202fPM.png\" alt width=\"335\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.04.39\u202fPM.png 608w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.04.39\u202fPM-300x175.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.04.39\u202fPM-580x338.png 580w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\"><\/a> &nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=KSA9xBXVa8s\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29980 alignnone\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.14.53\u202fPM-300x173.png\" alt width=\"339\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.14.53\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.14.53\u202fPM-580x334.png 580w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.14.53\u202fPM.png 612w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\"><\/a><\/p>\n<p><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\"><a href=\"https:\/\/www.youtube.com\/watch?v=KlUBAu5H264\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29985\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.27.50\u202fPM.png\" alt width=\"338\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.27.50\u202fPM.png 614w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.27.50\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.27.50\u202fPM-580x334.png 580w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\"><\/a>&nbsp; <a href=\"https:\/\/www.youtube.com\/watch?v=dz1YzVQOHs8\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29983\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.28.00\u202fPM.png\" alt width=\"337\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.28.00\u202fPM.png 608w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.28.00\u202fPM-300x174.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.28.00\u202fPM-580x336.png 580w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\"> &nbsp;<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=FcLcUP8Us_E\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29988\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM.png\" alt width=\"337\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM.png 948w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM-768x444.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM-860x497.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.21\u202fPM-580x335.png 580w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\"><\/a><\/span><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=DziohxlLV6c\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29990\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM.png\" alt width=\"336\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM.png 952w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM-300x174.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM-768x445.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM-860x499.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-3.36.32\u202fPM-580x336.png 580w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\"><\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/09\/1.png\"><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2023\/09\/2.png\"><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_por1kx5txo\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_lh3x5y6gef\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">\u00c9DITION 2019<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Du 02 au 06 octobre 2019&nbsp;:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=EePeWtpiqWg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29997\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM.png\" alt width=\"334\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM.png 952w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM-300x175.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM-768x449.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM-860x502.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.04.51\u202fPM-580x339.png 580w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\"><\/a> &nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=we3-uTJO8Iw\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30005\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM.png\" alt width=\"337\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM.png 948w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM-768x444.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM-860x497.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.15\u202fPM-580x335.png 580w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\"><\/a> &nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=6aui2i3n4rw\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29999\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM.png\" alt width=\"334\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM.png 950w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM-300x175.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM-768x448.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM-860x502.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.01\u202fPM-580x338.png 580w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\"><\/a>&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=WwHRMTc6WNA\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30003\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM.png\" alt width=\"336\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM.png 950w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM-300x174.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM-768x446.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM-860x500.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.05.28\u202fPM-580x337.png 580w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\">&nbsp;<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=EvmFd4uiZdc\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30010\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM.png\" alt width=\"334\" height=\"195\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM.png 950w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM-300x175.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM-768x448.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM-860x502.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.15.54\u202fPM-580x338.png 580w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_kp4v5cfxab\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_lampstyr26\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">\u00c9DITION 2017<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Du 04 au 08 octobre 2017.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=dgfBUYlthkQ\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30013\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM.png\" alt width=\"345\" height=\"200\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM.png 950w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM-300x174.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM-768x445.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM-860x498.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.20.15\u202fPM-580x336.png 580w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_5sq1a81bas\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_7i20o76uh8\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">\u00c9DITION 2015<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Du 22 sept. au 04 octobre 2015.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=n1Dk7kGjkJs\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30015\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM.png\" alt width=\"347\" height=\"200\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM.png 950w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM-768x443.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM-580x335.png 580w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.22.15\u202fPM-860x496.png 860w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_ed5h7x8n5\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_v9xq9b9cs\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">1\u00c8RE \u00c9DITION \u2013 2012<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Du 02 au 06 octobre 2012.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=wkyZhoA8QpE\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30021\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM.png\" alt width=\"346\" height=\"200\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM.png 952w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM-300x173.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM-768x444.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM-860x497.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.26.36\u202fPM-580x335.png 580w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_08n1zchju9\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_99uf1cq0bk\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_clients_slider_wrap enable_arrow_control\">\n<div id=\"cmsmasters_clients_n2vcdgot5a\" class=\"cmsmasters_owl_slider owl-carousel cmsmasters_clients_slider enable_arrow_control\" data-items=\"5\" data-single-item=\"false\" data-auto-play=\"5000\" data-slide-speed=\"1000\" data-pagination-speed=\"1000\" data-pagination=\"false\" data-navigation=\"true\"><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/region-bretagne.png\" alt=\"R\u00e9gion Bretagne\" title=\"R\u00e9gion Bretagne\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/rennes-vivre-en-intelligence.png\" alt=\"Rennes, Vivre en intelligence\" title=\"Rennes, Vivre en intelligence\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/les-tombees-de-la-nuit.jpg\" alt=\"Les Tomb\u00e9es de la Nuit\" title=\"Les Tomb\u00e9es de la Nuit\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/le-triangle.jpg\" alt=\"Le Triangle\" title=\"Le Triangle\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/ifa.jpg\" alt=\"Institut Franco-Am\u00e9ricain\" title=\"Institut Franco-Am\u00e9ricain\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/le-diapason.jpg\" alt=\"Le Diapason | Universit\u00e9 de Rennes 1\" title=\"Le Diapason | Universit\u00e9 de Rennes 1\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/les-champs-libres.png\" alt=\"Les Champs Libres\" title=\"Les Champs Libres\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/consulat-des-etats-unis-a-rennes.jpg\" alt=\"Consulat des \u00c9tats-Unis \u00e0 Rennes\" title=\"Consulat des \u00c9tats-Unis \u00e0 Rennes\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/1988-live-club.jpg\" alt=\"1988 Live Club\" title=\"1988 Live Club\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/adv.jpg\" alt=\"Ateliers du Vent\" title=\"Ateliers du Vent\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/ubu.png\" alt=\"Ubu\" title=\"Ubu\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/maison-de-quartier-la-touche.png\" alt=\"Maison de Quartier La Touche\" title=\"Maison de Quartier La Touche\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2019\/09\/apras.jpg\" alt=\"L'apras, le social partag\u00e9\" title=\"L'apras, le social partag\u00e9\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/sortir.png\" alt=\"Sortir ! Loisirs, sport &amp; culture pour tous\" title=\"Sortir ! Loisirs, sport &amp; culture pour tous\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/star.png\" alt=\"Star\" title=\"Star\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/radio-laser.png\" alt=\"Radio Laser\" title=\"Radio Laser\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/canal-b.png\" alt=\"Canal B\" title=\"Canal B\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/radio-rennes.png\" alt=\"Radio Rennes\" title=\"Radio Rennes\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/c-lab.png\" alt=\"C Lab\" title=\"C Lab\"><\/div><div class=\"cmsmasters_clients_item item cmsmasters_owl_slider_item\"><img decoding=\"async\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/09\/macadam.png\" alt=\"Macadam Basket\" title=\"Macadam Basket\"><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_pswmffoit\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_gv9srspugq\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_toggles toggles_mode_toggle\">\n<div class=\"cmsmasters_toggle_wrap\" data-tags=\"all \">\n<div class=\"cmsmasters_toggle_title\">\n<span class=\"cmsmasters_toggle_plus\">\n<span class=\"cmsmasters_toggle_plus_hor\"><\/span>\n<span class=\"cmsmasters_toggle_plus_vert\"><\/span>\n<\/span>\n<a href=\"#\">\u00c9DITION 2013 \u2013 10 ANS D\u2032ENGRENAGES<\/a>\n<\/div>\n<div class=\"cmsmasters_toggle\">\n<div class=\"cmsmasters_toggle_inner\">\n<p>Du 17 sept. au 20 octobre 2013.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=EZDKbwXfyRY\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30018\" src=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM.png\" alt width=\"344\" height=\"200\" srcset=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM.png 946w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM-300x174.png 300w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM-768x447.png 768w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM-860x500.png 860w, https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/06\/Capture-decran-2025-06-24-a-4.24.38\u202fPM-580x337.png 580w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":30046,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-26001","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes<\/title>\n<meta name=\"description\" content=\"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\" \/>\n<meta property=\"og:description\" content=\"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/\" \/>\n<meta property=\"og:site_name\" content=\"Engrenage[s]\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/engrenagesrennes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T08:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/bandeau-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/\",\"name\":\"Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/bandeau-web.jpg\",\"datePublished\":\"2017-09-07T13:03:41+00:00\",\"dateModified\":\"2025-09-16T08:20:12+00:00\",\"description\":\"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/bandeau-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/bandeau-web.jpg\",\"width\":1920,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/le-funk-prend-les-rennes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Funk prend les Rennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"name\":\"Engrenage[s]\",\"description\":\"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#organization\",\"name\":\"Engrenage[s]\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.engrenages.eu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo-retina.png\",\"width\":400,\"height\":100,\"caption\":\"Engrenage[s]\"},\"image\":{\"@id\":\"https:\\\/\\\/www.engrenages.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/engrenagesrennes\",\"https:\\\/\\\/www.instagram.com\\\/engrenages_rennes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagnieengrenage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","description":"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/","og_locale":"en_US","og_type":"article","og_title":"Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","og_description":"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.","og_url":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/","og_site_name":"Engrenage[s]","article_publisher":"https:\/\/www.facebook.com\/engrenagesrennes","article_modified_time":"2025-09-16T08:20:12+00:00","og_image":[{"width":1920,"height":550,"url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/bandeau-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/","url":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/","name":"Le Funk prend les Rennes - Engrenage[s], G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","isPartOf":{"@id":"https:\/\/www.engrenages.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/#primaryimage"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/bandeau-web.jpg","datePublished":"2017-09-07T13:03:41+00:00","dateModified":"2025-09-16T08:20:12+00:00","description":"Engrenage[s] organise tous les 2 ans \u201cLe Funk prend les Rennes\u201d, un rendez-vous festif \u00e0 l\u2019\u00e9chelle de la m\u00e9tropole rennaise.","breadcrumb":{"@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/#primaryimage","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/bandeau-web.jpg","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2025\/07\/bandeau-web.jpg","width":1920,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.engrenages.eu\/en\/le-funk-prend-les-rennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.engrenages.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Le Funk prend les Rennes"}]},{"@type":"WebSite","@id":"https:\/\/www.engrenages.eu\/en\/#website","url":"https:\/\/www.engrenages.eu\/en\/","name":"Engrenage[s]","description":"G\u00e9n\u00e9rateur de projets artistiques \u00e0 Rennes","publisher":{"@id":"https:\/\/www.engrenages.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.engrenages.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.engrenages.eu\/en\/#organization","name":"Engrenage[s]","url":"https:\/\/www.engrenages.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","contentUrl":"https:\/\/www.engrenages.eu\/wp-content\/uploads\/2017\/08\/logo-retina.png","width":400,"height":100,"caption":"Engrenage[s]"},"image":{"@id":"https:\/\/www.engrenages.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/engrenagesrennes","https:\/\/www.instagram.com\/engrenages_rennes\/","https:\/\/www.youtube.com\/user\/compagnieengrenage"]}]}},"_links":{"self":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages\/26001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/comments?post=26001"}],"version-history":[{"count":0,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/pages\/26001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media\/30046"}],"wp:attachment":[{"href":"https:\/\/www.engrenages.eu\/en\/wp-json\/wp\/v2\/media?parent=26001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}